{"id":959,"date":"2025-06-01T10:59:58","date_gmt":"2025-06-01T10:59:58","guid":{"rendered":"https:\/\/shaolintemplechina.com\/?p=959"},"modified":"2025-06-01T11:14:29","modified_gmt":"2025-06-01T11:14:29","slug":"was-ist-die-seele-der-shaolin-kultur","status":"publish","type":"post","link":"https:\/\/shaolintemplechina.com\/de\/what-is-the-soul-of-shaolin-culture\/","title":{"rendered":"Was ist die Seele der Shaolin-Kultur?"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Was ist die Seele der Shaolin-Kultur?<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-1024x768.jpg\" alt=\"shaolin kung fu zen\" class=\"wp-image-965\" srcset=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-1024x768.jpg 1024w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-300x225.jpg 300w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-768x576.jpg 768w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-1536x1152.jpg 1536w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-2048x1536.jpg 2048w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/shaolin-kung-fu-zen-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-1024x768.jpg\" alt=\"Shaolin-Kultur\" class=\"wp-image-966\" srcset=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-1024x768.jpg 1024w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-300x225.jpg 300w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-768x576.jpg 768w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-1536x1152.jpg 1536w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-2048x1536.jpg 2048w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/Shaolin-culture-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die Besonderheit des chinesischen Buddhismus liegt im Zen. Die Essenz der Shaolin-Kultur liegt ebenfalls im Zen. Die Shaolin-Kultur ist ein \"Organismus\" der buddhistischen Kultur, der mit dem Shaolin-Tempel als Plattform geschaffen, entwickelt, entfaltet, dargestellt und zusammengef\u00fchrt wurde. Ob es sich um Zen, Kampfkunst, Medizin, Astronomie, Architektur, und so weiter, verschiedene kulturelle Elemente, obwohl in sich geschlossene System, aber zwischen ihnen sind symbiotisch, komplement\u00e4r, gegenseitige Ursache und Wirkung, einander, so dass ein \"lebendiges\" kulturellen Organismus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Shaolin-Kultur ist jedoch keine typische Kulturform. Sie ist in der buddhistischen Kultur verwurzelt, und ihre Wurzeln liegen im Glauben des Buddhismus und dem Geist des Zen-Buddhismus. Das hei\u00dft, egal wie die anderen Elemente der Shaolin-Kultur bewegt, gedehnt oder zusammengezogen werden, sie k\u00f6nnen nicht von einem Zentrum getrennt werden, das das \"Zentrum\" des buddhistischen Glaubens oder des buddhistischen Geistes ist; kurz gesagt, der \"Zen-Geist\" ist die Seele der Shaolin-Kultur. Nimmt man \"Zen\" als \"Herz\" (Kern) - hier bezieht sich das Zen-Herz auf den Geist der Meditation und der L\u00e4uterung, den Geist der Transzendenz und der \u00dcberwindung, einen Charakter, einen Geist, eine Weisheit und ein Reich. Ob Shaolin-Kampfkunst oder Shaolin-Akademie, nur wenn wir an dieser Seele festhalten, k\u00f6nnen wir den inneren Charakter der Shaolin-Kultur voll zur Geltung bringen und einen dauerhaften Charme haben!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Menschen schenken dem Shaolin-Tempel ihre Aufmerksamkeit<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-768x1024.jpg\" alt=\"Was ist die Seele der Shaolin-Kultur?\" class=\"wp-image-963\" srcset=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-768x1024.jpg 768w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-225x300.jpg 225w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-1152x1536.jpg 1152w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-1536x2048.jpg 1536w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-9x12.jpg 9w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2025\/06\/What-is-the-soul-of-Shaolin-culture-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@shaolintemplechina\/video\/7507126232870341918\" data-video-id=\"7507126232870341918\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@shaolintemplechina\" href=\"https:\/\/www.tiktok.com\/@shaolintemplechina?refer=embed\" rel=\"nofollow noopener\">@shaolintemplechina<\/a> <p>Die kulturelle Bedeutung des Shaolin-Tempels geht weit \u00fcber die Kampfk\u00fcnste hinaus, er ist eine kulturelle Schatzkammer, die Chan, Philosophie, Kunst und Medizin integriert.<a title=\"Kungfu\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/kungfu?refer=embed\" rel=\"nofollow noopener\">#kungfu<\/a> <a title=\"chan\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/chan?refer=embed\" rel=\"nofollow noopener\">#chan<\/a> <a title=\"Kunst\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/art?refer=embed\" rel=\"nofollow noopener\">#art<\/a> <a title=\"Zeit\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/time?refer=embed\" rel=\"nofollow noopener\">#Zeit<\/a> <a title=\"Shaolin\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/shaolin?refer=embed\" rel=\"nofollow noopener\">#shaolin<\/a> <\/p> <a target=\"_blank\" title=\"\u266c Originalton - Shaolin-Tempel China\" href=\"https:\/\/www.tiktok.com\/music\/original-sound-7507126254336740127?refer=embed\" rel=\"nofollow noopener\">\u266c Originalton - Shaolin-Tempel China<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die Menschen achten auf <a href=\"https:\/\/shaolintemplechina.com\/de\/\">der Shaolin-Tempel<\/a>Aber im Moment geht es ihnen vor allem um Shaolin Wushu, die Funktionen und Reize der Kampfk\u00fcnste. Shaolin Wushu ist das Markenzeichen des Shaolin-Tempels. Wir betrachten die Shaolin-Kultur jedoch auf der Grundlage ihres allgemeinen und inneren Charmes, weshalb sich die Forscher besonders auf die Erforschung des inneren Geistes der Shaolin-Kultur konzentrieren m\u00fcssen. Als kulturelles Erbe der Menschheit sollten wir den inneren Geist des Shaolin Wushu sowie anderer Systeme erforschen und die Seele der darin enthaltenen Ideen erfassen. Ich stimme mit der Verwendung der vier Worte \"Zen-Herz und Kampfkunst\" \u00fcberein, die meiner Meinung nach die innere Beziehung zwischen dem \"Zen\" und dem \"Boxen\" der Shaolin treffend wiedergeben. In Analogie dazu kann das Studium der Shaolin-Kultur und der \"Shaolinologie\" den \"Umriss zusammenfassen\".<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Was die \"Shaolinologie\" betrifft, so m\u00f6chte ich einige unausgereifte Ansichten ansprechen<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Der erste Punkt, die \"Shaolinologie\" oder die Erkl\u00e4rung des menschlichen Kulturerbes der Shaolin, muss meines Erachtens den Wert einer Glaubenspositionierung erhalten. Seit langem wird in buddhistischen und Kampfkunstkreisen \u00fcber die Beziehung zwischen den Shaolin-Kampfk\u00fcnsten und dem Shaolin-Zen gestritten. Tats\u00e4chlich hat Herr Zhao Puchu zu Lebzeiten einmal eine Inschrift f\u00fcr den Shaolin-Tempel verfasst: \"Shaolin ist Zen, nicht Boxen\", was die Glaubensausrichtung und Werttendenz der Shaolin-Kultur klar definiert. Dieses \"Zen\" ist die Essenz, diese \"Kampfkunst\" ist der Tisch, einer f\u00fcr die Natur des K\u00f6rpers, einer f\u00fcr die Phase der Anwendung, zwischen den beiden ist wie die geistigen Ideen und der physische Ausdruck einer Person. Wushu ist kein rein k\u00f6rperlicher Sport, sondern eine Form von Wushu, die dem Zen-Geist entspringt. Dies entspricht dem spirituellen Streben des buddhistischen Glaubens, das die zuk\u00fcnftige Entwicklungsrichtung der \"Shaolinologie\" definieren und normieren kann. Die so genannte Wertepositionierung, d.h. der Shaolin-Tempel ist der Shaolin-Tempel, er ist ein Ort der Aktivit\u00e4t des buddhistischen Glaubens, diese \"Shaolinologie\" ist nicht weit von der sozialen Positionierung des Glaubens entfernt. Daher ist es im Forschungsprozess der \"Shaolinologie\" notwendig, die ideologische Konnotation der Shaolin-Kultur und die vielen Verhaltenspraktiken des Shaolin-Tempels zu analysieren und zu erforschen, ob sie mit den \u00dcberzeugungen des \"Buddhismus auf Erden\" \u00fcbereinstimmen, ob sie eine Umsetzungsform der gegenw\u00e4rtigen Welt sind? Meiner Meinung nach ist dies eine wichtige Frage, um den sozialen Wert der \"Shaolin-Studien\" zu erh\u00f6hen und die Richtung und Positionierung der zuk\u00fcnftigen Entwicklung der Shaolin-Kultur zu kl\u00e4ren, die es wert ist, sorgf\u00e4ltig untersucht zu werden.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@shaolintemplechina\/video\/7505197714255236383\" data-video-id=\"7505197714255236383\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@shaolintemplechina\" href=\"https:\/\/www.tiktok.com\/@shaolintemplechina?refer=embed\" rel=\"nofollow noopener\">@shaolintemplechina<\/a> <p>Wie man ein Shaolin-M\u00f6nch wird: Schritte, Ausbildung und Anforderungen. <a title=\"M\u00f6nch\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/monk?refer=embed\" rel=\"nofollow noopener\">#monk<\/a> <a title=\"Ausbildung\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/training?refer=embed\" rel=\"nofollow noopener\">#raining<\/a> <a title=\"Kungfu\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/kungfu?refer=embed\" rel=\"nofollow noopener\">#kungfu<\/a> <a title=\"shaolintempel\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/shaolintemple?refer=embed\" rel=\"nofollow noopener\">#shaolintempel<\/a> <a title=\"Wushu\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/wushu?refer=embed\" rel=\"nofollow noopener\">#wushu<\/a> <a title=\"Shaolin\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/shaolin?refer=embed\" rel=\"nofollow noopener\">#shaolin<\/a> @TikTok @TikTok Trends <\/p> <a target=\"_blank\" title=\"\u266c Originalton - Shaolin-Tempel China\" href=\"https:\/\/www.tiktok.com\/music\/original-sound-7505197697478003487?refer=embed\" rel=\"nofollow noopener\">\u266c Originalton - Shaolin-Tempel China<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@shaolintemplechina\/video\/7502311569833921823\" data-video-id=\"7502311569833921823\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@shaolintemplechina\" href=\"https:\/\/www.tiktok.com\/@shaolintemplechina?refer=embed\" rel=\"nofollow noopener\">@shaolintemplechina<\/a> <p>gongfu ausbildung in china shaolin-tempel <a title=\"M\u00f6nch\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/monk?refer=embed\" rel=\"nofollow noopener\">#monk<\/a> <a title=\"china\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/china?refer=embed\" rel=\"nofollow noopener\">#china<\/a> <a title=\"Shaolin\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/shaolin?refer=embed\" rel=\"nofollow noopener\">#shaolin<\/a> <a title=\"\u4e2d\u56fd\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/%E4%B8%AD%E5%9B%BD?refer=embed\" rel=\"nofollow noopener\">#\u4e2d\u56fd<\/a> <a title=\"\u4e2d\u56fd\u529f\u592b\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/%E4%B8%AD%E5%9B%BD%E5%8A%9F%E5%A4%AB?refer=embed\" rel=\"nofollow noopener\">#\u4e2d\u56fd\u529f\u592b<\/a> <a title=\"shaolintempel\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/shaolintemple?refer=embed\" rel=\"nofollow noopener\">#shaolintempel<\/a> <\/p> <a target=\"_blank\" title=\"\u266c Originalton - \u2728 Forever Young \u2728 - \u2728 Forever Young \u2728\" href=\"https:\/\/www.tiktok.com\/music\/original-sound-\u2728-Forever-Young-\u2728-7431726676658244353?refer=embed\" rel=\"nofollow noopener\">\u266c Originalton - \u2728 Forever Young \u2728 - \u2728 Forever Young \u2728<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zweitens, da Shaolin Wushu und andere kulturelle Systeme sind auch auf die Weisheit des Zen-Buddhismus zugeschrieben, dann, in der Studie von \"Shaolinology\", ich glaube, dass die Interpretation von vielen Shaolin Wushu Routinen k\u00f6nnen den Wert und die Bedeutung der Idee der \"Zenology\" gegeben werden. Zum Beispiel, einige Kampfk\u00fcnstler analysieren die Kampfkunst-Routinen, wenn sie \u00fcber die Assoziation und die Merkmale der Absicht, Gas, Steifigkeit, Flexibilit\u00e4t, etc. sprechen, oft mit \"geheimnisvoll und unerkl\u00e4rlich\" zum Ausdruck bringen, die bereits die Konnotation von \"Gedanken\" und den Wert des Glaubens hat. Ob die Absicht des Qi ausgel\u00f6st, starr und flexibel, ich denke, es ist in der Form, Kampfk\u00fcnste auf der realen geheimnisvollen und unerkl\u00e4rlichen Bereich gesetzt, absolut nicht Kampfk\u00fcnste gesetzt werden kann reflektiert und ausgedr\u00fcckt, die tats\u00e4chlich in der \"Zen-Herz-Transport Kampfk\u00fcnste\" Konzept verk\u00f6rpert ist. Dies ist auch wahr. Die wirkliche Kampfkunst Meister ist definitiv nicht in einer Bewegung, die so genannte Absicht zu, Gas zu, Kraft zu, vor allem, ist eine Art von konzeptionellen, den Geist auf die freie Freigabe, die Macht auf die St\u00e4rke der Grad der St\u00e4rke und Schw\u00e4che. Das ist dasselbe wie das zen-buddhistische Konzept, alle Gedanken loszulassen und der Natur ihren Lauf zu lassen. Auch im Prozess der Zen-Praxis, der Zen-Geistesschulung, die eigentlich eine tiefe, tiefe Reaktion des Geistes auf eine Form ist, werden zum Beispiel Starrheit und Flexibilit\u00e4t angewandt.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monks.jpg\" alt=\"\" class=\"wp-image-714\" srcset=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monks.jpg 640w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monks-300x225.jpg 300w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monks-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"448\" src=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monk.jpg\" alt=\"Shaolin-Buddhismus-M\u00f6nch\" class=\"wp-image-713\" srcset=\"https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monk.jpg 640w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monk-300x210.jpg 300w, https:\/\/shaolintemplechina.com\/wp-content\/uploads\/2024\/12\/shaolin-buddhism-monk-18x12.jpg 18w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Meiner Meinung nach m\u00fcssen beim Studium der Shaolinologie sowohl die Kampfk\u00fcnstler als auch die Zen-Gelehrten eine angemessene, harmonische und enge Kooperationsbeziehung aufbauen. Deshalb muss man beim Studium des Shaolin Wushu, egal welche Richtung man in der Kampfkunst einschl\u00e4gt, diese grundlegende \"Zen\"-Kultivierung haben. Ich glaube sogar, dass der Wert von Shaolin Wushu in Zukunft noch gr\u00f6\u00dfer sein wird, wenn es mit der Idee des \"Zen\" neu interpretiert wird.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Drittens habe ich auf der Grundlage der obigen \u00dcberlegungen die konkrete Vorstellung, dass der Shaolin-Tempel als Urheimat des chinesischen Zen-Buddhismus seinen geb\u00fchrenden Beitrag zur Weiterf\u00fchrung des Geistes des Zen-Buddhismus leisten sollte. Das hei\u00dft, \"Shaolinology\" kann nicht nur in der \"Lernen\", sollte es auch \"Praxis\", so dass die Kombination von Lernen und Praxis, um die Shaolin-Kultur in die Realit\u00e4t, in die Herzen der Menschen. Daher schlage ich vor, in der Shaolin landschaftlichen Bereich kann eine internationale, riesige Kapazit\u00e4t Meditationszentrum zu bauen, f\u00fcr verschiedene kulturelle Hintergr\u00fcnde auf der ganzen Welt der Shaolin-Kultur-Enthusiasten, chinesische buddhistische Kultur Gl\u00e4ubigen, eine feierliche St\u00e4tte f\u00fcr das Studium bieten, so dass jeder hier \"Moral und Fitness zu erh\u00f6hen\" \"Zen Yue Das Zentrum bietet einen feierlichen Ort f\u00fcr alle zu \"kultivieren Tugend und Fitness\" und \"Zen Freude und Weisheit\".<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\">Zusammenfassung<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Meditationszentrum sollte nicht einfach nur eine \"Meditationshalle\" sein, die durch ein Geb\u00e4ude errichtet wird, sondern es sollte entsprechend den buddhistischen \u00dcberzeugungen und der ideologischen Bedeutung der Shaolin-Kultur mit den entsprechenden Dharma-Ritualen und -Formen eingerichtet werden, um einem breiten Spektrum von Gr\u00fcnden gerecht zu werden und den Bed\u00fcrfnissen der Situation zu entsprechen. Es wird davon ausgegangen, dass es nach ernsthaftem Studium und ernsthafter Praxis, der Kultivierung der Moral und der Steigerung der Weisheit von gro\u00dfer praktischer Bedeutung ist, die Herzen der Menschen und die Gesellschaft zu reinigen und gemeinsam eine harmonische Gesellschaft aufzubauen.<\/p>","protected":false},"excerpt":{"rendered":"<p>What is the soul of Shaolin culture? The specialty of Chinese Buddhism lies in Zen. The essence of Shaolin culture also lies in Zen. Shaolin culture is an \u201corganism\u201d of Buddhist culture created, developed, evolved, displayed and coalesced with Shaolin Temple as a platform. Whether it is Zen, martial arts, medicine, astronomy, architecture, and so [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-959","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/posts\/959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/comments?post=959"}],"version-history":[{"count":3,"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/posts\/959\/revisions"}],"predecessor-version":[{"id":970,"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/posts\/959\/revisions\/970"}],"wp:attachment":[{"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/media?parent=959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/categories?post=959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shaolintemplechina.com\/de\/wp-json\/wp\/v2\/tags?post=959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}